{"id":858,"date":"2023-11-14T09:06:27","date_gmt":"2023-11-14T08:06:27","guid":{"rendered":"https:\/\/kpi-consult-staudinger.com\/?p=858"},"modified":"2025-04-30T18:06:45","modified_gmt":"2025-04-30T16:06:45","slug":"lithium-als-bestandteil-der-energie-und-waermewende-2","status":"publish","type":"post","link":"https:\/\/kpi-consult-staudinger.com\/de\/2023\/11\/14\/lithium-als-bestandteil-der-energie-und-waermewende-2\/","title":{"rendered":"Lithium als Bestandteil der Energie- und W\u00e4rmewende?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=&#8220;855&#8243; img_size=&#8220;full&#8220;][vc_column_text]Wer die Weltpresse zum Thema \u201eRohstoffe\u201c verfolgt, liest immer wieder, dass Lithium sich zu einem der wichtigsten Faktoren f\u00fcr innovative Technologien entwickelt hat.<\/p>\n<p>In jedem Elektroauto, in jedem Fahrradakku, in jedem Handy ist Lithium nahezu unverzichtbar.<\/p>\n<p>&nbsp;<\/p>\n<p>Neuere Erkenntnisse (siehe z.B. KIT in Karlsruhe: <a href=\"https:\/\/www.kit.edu\/kit\/pi_2023_066_nachhaltiges-lithium-fuer-viele-jahrzehnte.php\">https:\/\/www.kit.edu\/kit\/pi_2023_066_nachhaltiges-lithium-fuer-viele-jahrzehnte.php<\/a>) zeigen nun, dass die seit l\u00e4ngerem schon vermuteten, gr\u00f6\u00dferen Lithium-Vorkommen im Tiefenwasser des Oberrheingrabens vorhanden sind. Sie geben Geothermie-Firmen der Region und vielleicht auch weiteren ganz neue Perspektiven:<\/p>\n<p>Wenn mit der aufw\u00e4ndigen Exploration und Erschlie\u00dfung von lukrativen Geothermie-Feldern als \u201eZusatznutzen\u201c noch die M\u00f6glichkeit zur Lithiumgewinnung abfallen w\u00fcrde, dann lie\u00dfe sich so manche Bohrung deutlich besser finanzieren.<\/p>\n<p>&nbsp;<\/p>\n<p>Als Resultat w\u00e4re sicherlich in Deutschland ein h\u00f6heres Interesse an entsprechenden Explorationsprojekten mit verbesserter Technologie und gr\u00f6\u00dferer Akzeptanz in Politik und Bev\u00f6lkerung zu erwarten.<\/p>\n<p>&nbsp;<\/p>\n<p>Bei entsprechender Umsetzung k\u00f6nnten Ballungszentren in der N\u00e4he von solchen Projekten mit \u201egr\u00fcner Nah-\/Fernw\u00e4rme\u201c versorgt werden bzw. entsprechende Zielprojekte in den zu erstellenden kommunalen W\u00e4rmepl\u00e4nen rechtzeitig verankert werden. Gleichzeitig erg\u00e4be sich ein neues, lukratives Gesch\u00e4ftsfeld f\u00fcr die Energieversorger und die Stadtwerke, die in absehbarer Zeit auf gr\u00f6\u00dfere Teile ihres Gasgesch\u00e4ftes werden verzichten m\u00fcssen.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Gewinnung von Lithium in Deutschland w\u00fcrde vermutlich zus\u00e4tzlich die Herstellung von Batterien in Deutschland positiv beeinflussen und somit auch positiv auf die Verkehrswende einzahlen.<\/p>\n<p>&nbsp;<\/p>\n<p>Alles in allem eine \u201eWin-Win-Situation\u201c, so wie es sich jetzt abzeichnet. Wenn jetzt von allen Seiten z\u00fcgig agiert wird, dann k\u00f6nnte Lithium in Deutschland tats\u00e4chlich zum Bestandteil der W\u00e4rmewende werden.[\/vc_column_text]<style>.ld_spacer_6a5719e12642e{height:60px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a5719e12642e\"><span class=\"liquid_empty_space_inner\"><\/span><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wer die Weltpresse zum Thema \u201eRohstoffe\u201c verfolgt, liest immer wieder, dass Lithium sich zu einem der wichtigsten Faktoren f\u00fcr innovative Technologien entwickelt hat.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-858","post","type-post","status-publish","format-standard","hentry","category-strategieberatung"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":2,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/858\/revisions"}],"predecessor-version":[{"id":897,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/858\/revisions\/897"}],"wp:attachment":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/categories?post=858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/tags?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}