{"id":816,"date":"2022-10-26T09:00:22","date_gmt":"2022-10-26T07:00:22","guid":{"rendered":"https:\/\/kpi-consult-staudinger.com\/?p=816"},"modified":"2025-05-05T12:14:03","modified_gmt":"2025-05-05T10:14:03","slug":"marktupdate-waerme-und-kaelte-wachsen-zusammen","status":"publish","type":"post","link":"https:\/\/kpi-consult-staudinger.com\/de\/2022\/10\/26\/marktupdate-waerme-und-kaelte-wachsen-zusammen\/","title":{"rendered":"MARKTUPDATE: W\u00e4rme und K\u00e4lte wachsen zusammen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=&#8220;818&#8243; img_size=&#8220;full&#8220;][vc_column_text]Wer vorletzte Woche auf der Chillventa in N\u00fcrnberg war, der hat gesehen, dass viele Hersteller, die man bisher aus dem K\u00e4lte-\/Klimabereich kannte, jetzt auch W\u00e4rmepumpen anbieten.<\/p>\n<p>&nbsp;<\/p>\n<p>Technologisch ist dies eigentlich keine \u00dcberraschung, ist doch der von Carl von Linde vor mehr als 100 Jahren erfundene K\u00e4ltekreis in der Umkehrung auch als W\u00e4rmeerzeuger nutzbar.<\/p>\n<p>Aber erst jetzt, mit der Gas-Krise, der Klima-Krise und der starken Verteuerung von fossilen Brennstoffen, schiebt sich die W\u00e4rmepumpentechnologie in den Vordergrund und damit auch Hersteller, die im K\u00e4ltekreis \u201ezuhause\u201c sind.<\/p>\n<p>&nbsp;<\/p>\n<p>Was hei\u00dft das f\u00fcr den Markt?<\/p>\n<ul>\n<li>Das Herstellerportfolio f\u00fcr W\u00e4rmeerzeuger w\u00e4chst in Summe<\/li>\n<li>Hersteller aus den warmen Regionen der Welt, also dort, wo bisher vorrangig Klimager\u00e4te im Einsatz sind, dr\u00e4ngen jetzt mit W\u00e4rmepumpen nach Europa, siehe Aussteller auf der Chillventa<\/li>\n<li>Bisherige reine Heizungshersteller bieten jetzt auch aktiv Klima-\/K\u00e4ltetechnik an<\/li>\n<li>Die Verf\u00fcgbarkeit von wesentlichen Komponenten wie z.B. Verdichter, Ventilatoren, W\u00e4rmetauscher ist kritisch und wird es sicher noch einige Zeit bleiben<\/li>\n<li>Neben den Gewerken der Heizungsbauer und Gas-\/Wasser-Installateure sind auch K\u00e4lteanlagenbauer und Elektriker, z.T. mit Zusatzausbildung, im Heizungsbau \u201eunterwegs\u201c<\/li>\n<li>Auch der Handel f\u00fcr K\u00e4lte\/Klima r\u00fcstet zum Thema W\u00e4rmepumpe auf und sieht zus\u00e4tzliche Gesch\u00e4ftspotenziale<\/li>\n<li>F\u00fcr das Fachhandwerk wird auch bei mittleren und kleineren Betrieben der Bedarf an breiterer Ausbildung bzw. Kompetenz in Hinblick auf den K\u00e4ltekreis wachsen. Auf Dauer ist vermutlich ein neues Berufsbild, dann vermutlich auch unter Einbindung von PV\/Elektro, zu erwarten.<\/li>\n<li>Die Vertriebskan\u00e4le werden mehr werden und auch zunehmend die B2C-Versionen miteinschlie\u00dfen<\/li>\n<\/ul>\n<p>Das gro\u00dfe Besucherinteresse auf der Chillventa hat gezeigt, dass Heizung und Klima in Zukunft in vielen F\u00e4llen gemeinsam gedacht und behandelt werden m\u00fcssen.<\/p>\n<p>W\u00e4rme und K\u00e4lte wachsen zusammen!<\/p>\n<p>Die Marktteilnehmer werden sich darauf einstellen m\u00fcssen, und das sehr h\u00e4ufig schneller als den meisten lieb ist.[\/vc_column_text]<style>.ld_spacer_6a5719df90ccf{height:60px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a5719df90ccf\"><span class=\"liquid_empty_space_inner\"><\/span><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wer vorletzte Woche auf der Chillventa in N\u00fcrnberg war, der hat gesehen, dass viele Hersteller, die man bisher aus dem K\u00e4lte-\/Klimabereich kannte, jetzt auch W\u00e4rmepumpen anbieten.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-816","post","type-post","status-publish","format-standard","hentry","category-strategieberatung"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/comments?post=816"}],"version-history":[{"count":3,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/816\/revisions"}],"predecessor-version":[{"id":903,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/816\/revisions\/903"}],"wp:attachment":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/media?parent=816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/categories?post=816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/tags?post=816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}