{"id":749,"date":"2021-12-01T13:25:26","date_gmt":"2021-12-01T12:25:26","guid":{"rendered":"https:\/\/kpi-consult-staudinger.com\/?p=749"},"modified":"2021-12-01T13:25:26","modified_gmt":"2021-12-01T12:25:26","slug":"digitaler-360-vertrieb-der-durchbruch-der-videokonferenz","status":"publish","type":"post","link":"https:\/\/kpi-consult-staudinger.com\/de\/2021\/12\/01\/digitaler-360-vertrieb-der-durchbruch-der-videokonferenz\/","title":{"rendered":"Digitaler 360\u00b0-Vertrieb: Der Durchbruch der Videokonferenz"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=&#8220;751&#8243; img_size=&#8220;full&#8220;][vc_column_text]Nach zwei Lockdowns und einem Sommer 2021, der f\u00fcr die meisten Vertriebler sicher ein befreiendes Gef\u00fchl brachte, steigt aktuell wieder die Unsicherheit \u2013 wie wird sich das Gesch\u00e4ft unter m\u00f6glichen neuen Corona-Ma\u00dfnahmen weiterentwickeln? Und ganz praktisch: Was machen all die Au\u00dfendienstmitarbeiter, die vielleicht wieder weniger physisch bei Kunden sein k\u00f6nnen, um so nachhaltige Beziehungen aufzubauen und zu pflegen?<\/p>\n<p>Nun, vielleicht m\u00fcssen sie das auch gar nicht mehr. Zumindest nicht in dem Ma\u00dfe, wie es bisher gewohnt war. Denn die alles ver\u00e4ndernde Digitalisierung er\u00f6ffnet dem Vertriebsmanagement neue Chancen f\u00fcr mehr Wachstum. Doch moderne Technik hin oder her, ganz ehrlich: Kann man im Au\u00dfendienst mit Homeoffice erfolgreich sein?<\/p>\n<p>Ja, das kann man.<\/p>\n<p>Bisher gilt: Telefon, Mails, Chats oder Messages m\u00fcssen reichen, ist ohnehin schlie\u00dflich alles nur zweite Wahl. Das reale Treffen ist das, worauf es ankommt, so der allgemeine Konsens. Und klar, das Zwischenmenschliche spielt im Vertrieb eine zentrale Rolle und wird das auch in Zukunft tun, doch man wird zunehmend sehen, wie gro\u00df der Mehrwert durch die M\u00f6glichkeiten digitaler Kan\u00e4le f\u00fcr den Vertrieb ist \u2013 digitaler Vertrieb ist nichts anderes als die n\u00e4chste Evolutionsstufe des intelligenten Vertriebs. Analog zur Marketingkommunikation k\u00f6nnte man auch sagen: 360\u00b0-Vertrieb.<\/p>\n<p>Wie funktioniert dieser \u201eneue\u201c Vertrieb?<\/p>\n<p>Kurz erkl\u00e4rt, gibt es einen zentralen Ausgangspunkt: die Videokonferenz. Nach vielen Jahren mangelnder Akzeptanz hat sie sich gezwungenerma\u00dfen von heute auf morgen etabliert. Und das ist gut so. Denn sie kommt dem physischen Zusammentreffen am n\u00e4chsten, sie liefert eine Kommunikationsplattform, die Aufmerksamkeit, Informationssammlung und eine gewisse Verbindlichkeit erm\u00f6glicht \u2013 und liefert ein (multi-)mediales Setting, das die Vertriebsarbeit qualitativ besser macht. Vorausgesetzt man erkennt, worauf es ankommt. Wir haben die wichtigsten sechs Learnings kurz und knapp zusammengefasst:<\/p>\n<ol>\n<li><strong>Termin-Setup optimieren<br \/>\n<\/strong>Erst in Videokonferenzen, wenn der Blickkontakt und die non-verbale Abstimmung erschwert ist, wird so richtig klar, wie wichtig es ist, ein klares Setup f\u00fcr den Termin zu definieren: Wer moderiert? Wer f\u00fchrt durch die Pr\u00e4sentation? Wer reagiert auf welche Fragen? Die Rollenverteilung, die bei realen Meetings viel zu h\u00e4ufig der Improvisation \u00fcberlassen wird, ist vorab eindeutig zu kl\u00e4ren. Nur so l\u00e4sst sich Struktur, Effizienz und Diskussionssteuerung herstellen \u2013 ohne unangenehme Stille, Durcheinanderreden und Missverst\u00e4ndnisse.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li><strong>Kunden bewusst wahrnehmen<br \/>\n<\/strong>Auch wenn die Videokonferenz vergleichsweise nah an das physische Treffen herankommt, so fehlen doch wichtige Sinneswahrnehmungen zur Feststellung m\u00f6glicher Spannungen oder Unstimmigkeiten. Es ist deshalb umso wichtiger, mit bewusst gesch\u00e4rften Sinnen in ein Kundenmeeting zu gehen \u2013 vor allem im Falle eines Neukundengespr\u00e4chs.<br \/>\nDas hei\u00dft konkret: Genau zuh\u00f6ren, versuchen, verbale Nuancen zu sp\u00fcren.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li><strong>Nutzen klar herausarbeiten<br \/>\n<\/strong>Anders als bei den meisten physischen Meetings ist die effektive Meetingzeit auf den terminierten Zeitslot beschr\u00e4nkt. Es sind fast keine informellen Randgespr\u00e4che vor Beginn oder nach Ende des Meetings vorhanden. Deshalb gilt: Jedes Meeting ist wie ein Elevator Pitch zu sehen. Man braucht einen ganz klaren Plan, wie man sein Angebot und insbesondere den Nutzen des Kunden darstellt \u2013 aufsetzend auf vorab recherchierten und antizipierbaren Kundenproblemen bzw. -zielen. Dieser Plan muss sich dann auch in einer (m\u00f6glichst pr\u00e4gnanten) Pr\u00e4sentation wiederfinden, die sp\u00e4testens seit Videokonferenzen zum Standard geworden sein sollte. Vor allem f\u00fcr die Neukundengewinnung braucht es eine exzellente Vorstellungspr\u00e4sentation.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li><strong>Content einbinden<br \/>\n<\/strong>Das besonders positive am neuen \u201eZwang\u201c zur Pr\u00e4sentation: Die multimediale Plattform, die sie bietet. Durch den Einsatz verschiedener Content-Formate kann ein viel st\u00e4rkerer Eindruck des Unternehmens, der Marke und des konkreten Angebots erzeugt werden. Von Imagefilmen \u00fcber Casefilme bis hin zur Einbettung von Service\/Help Content kann der Kunde innerhalb der Pr\u00e4sentation regelrecht eine Customer Journey erleben \u2013 zugeschnitten auf seinen individuellen Bedarf. Was es dazu braucht? Eine enge Zusammenarbeit zwischen Vertrieb und Marketing, organisationell und prozessual verankert \u2013 und vor allem inhaltlich getrieben, mit vollem Fokus auf den einzelnen Kunden. Ohne Marketing kein 360\u00b0-Vertrieb.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li><strong>Interaktions-Tools einsetzen<br \/>\n<\/strong>F\u00fcr erfolgreiche Vertriebsarbeit braucht es eine konsequente Dokumentation. Doch gute Meeting-Protokoll-Kulturen sind selten. Auch Whiteboards oder Flipcharts werden viel zu selten eingesetzt. Genau hier machen digitale Tools die Vertriebsarbeit ein St\u00fcck besser und effizienter. Der smarte Einsatz von Interaktions-Tools w\u00e4hrend der Videokonferenz kann die Dokumentation nicht nur \u201eautomatisch\u201c erfolgen lassen, sondern erh\u00f6ht auch die generelle Partizipation, meistens auch die Qualit\u00e4t der Aussagen und dar\u00fcber hinaus deren Verbindlichkeit.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li><strong>N\u00e4chste Schritte klar definieren<br \/>\n<\/strong>W\u00e4hrend bei physischen Meetings h\u00e4ufig wie selbstverst\u00e4ndlich ein Anschlusstermin mit ToDos definiert wird, enden digitale Termine schnell im Unklaren, was die n\u00e4chsten Schritte angeht. Um gerade bei Neukundengespr\u00e4chen trotz der geringeren gef\u00fchlten Verbindlichkeit eine Fortsetzung sicherzustellen und erneut gut vorbereiten zu k\u00f6nnen, muss ein noch h\u00f6heres Augenmerk auf die klare Zusammenfassung des Gespr\u00e4chs und die Definition der Next Steps gelegt werden. Auch hier wird die Vertriebsarbeit durch den digitalen Kanal letztlich qualitativ besser und effizienter.<\/li>\n<\/ol>\n<p>Die Lernkurve ist aktuell sehr steil, der digitale 360\u00b0-Vertrieb entwickelt sich entsprechend schnell weiter \u2013 auch ohne weitere Lockdowns. Wir helfen Ihnen, schneller zu sein als der Wettbewerb und dar\u00fcber Ihre Sales Performance zu steigern.<\/p>\n<p>Sie m\u00f6chten Ihren Vertrieb auf diese digitale Zukunft ausrichten? Sie brauchen ganz konkret eine \u00fcberzeugende Vertriebspr\u00e4sentation, die Ihren Au\u00dfendienst beim Kunden herausstechen l\u00e4sst?<\/p>\n<p><strong>Wir helfen Ihnen gerne.<\/strong><br \/>\n<strong>Mit \u00fcber 30 Jahren marktf\u00fchrender Erfahrung in Vertrieb &amp; Marketing.<\/strong><\/p>\n<p><strong>Kontaktieren Sie uns f\u00fcr n\u00e4here Informationen.<\/strong>[\/vc_column_text]<style>.ld_spacer_6a049cdd5baa5{height:60px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a049cdd5baa5\"><span class=\"liquid_empty_space_inner\"><\/span><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wie wird sich das Gesch\u00e4ft unter m\u00f6glichen neuen Corona-Ma\u00dfnahmen weiterentwickeln? Kann man im Au\u00dfendienst mit Homeoffice erfolgreich sein?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-749","post","type-post","status-publish","format-standard","hentry","category-prozessberatung"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/comments?post=749"}],"version-history":[{"count":1,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/749\/revisions"}],"predecessor-version":[{"id":753,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/posts\/749\/revisions\/753"}],"wp:attachment":[{"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/media?parent=749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/categories?post=749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpi-consult-staudinger.com\/de\/wp-json\/wp\/v2\/tags?post=749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}